{"id":90,"date":"2020-05-28T09:47:31","date_gmt":"2020-05-28T07:47:31","guid":{"rendered":"https:\/\/smartwag.com\/?page_id=90"},"modified":"2026-06-20T12:06:46","modified_gmt":"2026-06-20T10:06:46","slug":"rechtliche-hinweise","status":"publish","type":"page","link":"https:\/\/smartwag.com\/de\/mentions-legales\/","title":{"rendered":"Rechtliche Hinweise"},"content":{"rendered":"<h3>1. Vorstellung der Website.<\/h3>\n<p>Gem\u00e4\u00df Artikel 6 des Gesetzes Nr. 2004-575 vom 21. Juni 2004 \u00fcber das Vertrauen in die digitale Wirtschaft wird den Nutzern der Website Folgendes mitgeteilt\u00a0<a href=\"http:\/\/http\/\/smartwag.com\/\/\">https:\/\/smartwag.com\/<\/a>\u00a0die Identit\u00e4t der verschiedenen Personen, die an seiner Durchf\u00fchrung und Nachbereitung beteiligt sind :<\/p>\n<p><strong>Propri\u00e9taire<\/strong> SMART WAG S\u00e0rl - Gesellschaft mit beschr\u00e4nkter Haftung, eingetragen im Handelsregister des Zentralwallis unter der Nummer CHE-321.644.765 - Chemin de la Chapelle (Weg der Kapelle), 2 3960 Loc - Crans Montana Schweiz<br \/>\n<strong>Responsable publication<\/strong> : info@smartwag.com<br \/>\nDer Verantwortliche f\u00fcr die Ver\u00f6ffentlichung ist eine nat\u00fcrliche Person oder eine juristische Person.<br \/>\n<strong>Webmaster<\/strong> :\u00a0 customerservice@smartwag.com<br \/>\n<strong>H\u00e9bergeur<\/strong> : OVH SAS :\u00a02 rue Kellermann \u2013 BP 80157 59053 ROUBAIX CEDEX 1 \u2013 France<\/p>\n<h3>2. Allgemeine Bedingungen f\u00fcr die Nutzung der Website und der angebotenen Dienste.<\/h3>\n<p>Die Nutzung der Seite\u00a0<a href=\"http:\/\/http\/\/smartwag.com\/\/\">https:\/\/smartwag.com\/<\/a>\u00a0bedeutet die vollst\u00e4ndige und uneingeschr\u00e4nkte Annahme der nachstehend beschriebenen allgemeinen Nutzungsbedingungen. Diese Nutzungsbedingungen k\u00f6nnen jederzeit ge\u00e4ndert oder erg\u00e4nzt werden, wobei die Nutzer der Website\u00a0<a href=\"http:\/\/http\/\/smartwag.com\/\/\">https:\/\/smartwag.com\/<\/a>\u00a0sind daher aufgefordert, sie regelm\u00e4\u00dfig zu konsultieren.<\/p>\n<p>Diese Website ist normalerweise jederzeit f\u00fcr die Nutzer zug\u00e4nglich. SMART WAG S\u00e0rl kann jedoch aufgrund technischer Wartungsarbeiten eine Unterbrechung vornehmen und wird sich bem\u00fchen, die Nutzer vorab \u00fcber die Daten und Zeiten des Eingriffs zu informieren.<\/p>\n<p>Die Website\u00a0<a href=\"http:\/\/http\/\/smartwag.com\/\/\">https:\/\/smartwag.com\/<\/a>\u00a0wird regelm\u00e4\u00dfig vom Webmaster aktualisiert. Ebenso k\u00f6nnen die rechtlichen Hinweise jederzeit ge\u00e4ndert werden: Sie sind jedoch f\u00fcr den Nutzer verbindlich, der sie so oft wie m\u00f6glich lesen sollte, um sie zur Kenntnis zu nehmen.<\/p>\n<h3>3. Beschreibung der erbrachten Dienstleistungen.<\/h3>\n<p>Die Website\u00a0<a href=\"http:\/\/http\/\/smartwag.com\/\/\">https:\/\/smartwag.com\/<\/a>\u00a0hat zum Ziel, Informationen \u00fcber alle Aktivit\u00e4ten des Unternehmens bereitzustellen.<\/p>\n<p>SMART WAG S\u00e0rl bem\u00fcht sich, auf der Website Folgendes zur Verf\u00fcgung zu stellen <a href=\"http:\/\/http\/\/smartwag.com\/\/\">https:\/\/smartwag.com\/<\/a>\u00a0so genaue Informationen wie m\u00f6glich. Er kann jedoch nicht f\u00fcr Auslassungen, Ungenauigkeiten und M\u00e4ngel in der Aktualisierung haftbar gemacht werden, unabh\u00e4ngig davon, ob diese durch ihn oder durch dritte Partner, die ihm diese Informationen zur Verf\u00fcgung stellen, verursacht wurden.<\/p>\n<p>Alle auf der Seite angegebenen Informationen\u00a0<a href=\"http:\/\/http\/\/smartwag.com\/\/\">https:\/\/smartwag.com\/<\/a>\u00a0sind unverbindlich und k\u00f6nnen sich \u00e4ndern. Dar\u00fcber hinaus sind die Informationen auf der Website\u00a0<a href=\"http:\/\/http\/\/smartwag.com\/\/\">https:\/\/smartwag.com\/<\/a>\u00a0sind nicht ersch\u00f6pfend. Sie werden vorbehaltlich der \u00c4nderungen gegeben, die seit ihrer Online-Ver\u00f6ffentlichung vorgenommen wurden.<\/p>\n<h3>4. Vertragliche Einschr\u00e4nkungen der technischen Daten.<\/h3>\n<p>Die Website verwendet die JavaScript-Technologie.<\/p>\n<p>Die Website kann nicht f\u00fcr materielle Sch\u00e4den im Zusammenhang mit der Nutzung der Website haftbar gemacht werden. Dar\u00fcber hinaus verpflichtet sich der Nutzer der Website, auf die Website mit einer aktuellen Hardware zuzugreifen, die keine Viren enth\u00e4lt und \u00fcber einen Browser der neuesten Generation verf\u00fcgt, der auf dem neuesten Stand ist.<\/p>\n<h3>5. Geistiges Eigentum und F\u00e4lschungen.<\/h3>\n<p>SMART WAG S\u00e0rl ist Eigent\u00fcmer der geistigen Eigentumsrechte oder besitzt die Nutzungsrechte f\u00fcr alle auf der Website zug\u00e4nglichen Elemente, insbesondere Texte, Bilder, Grafiken, Logos, Icons, T\u00f6ne, Software.<\/p>\n<p>Jede Vervielf\u00e4ltigung, Darstellung, \u00c4nderung, Ver\u00f6ffentlichung und Anpassung aller oder eines Teils der Elemente der Website, unabh\u00e4ngig von den verwendeten Mitteln oder Verfahren, ist untersagt, es sei denn, es liegt eine vorherige schriftliche Genehmigung von : SMART WAG S\u00e0rl.<\/p>\n<p>Jede nicht genehmigte Nutzung der Website oder eines ihrer Elemente wird als F\u00e4lschung angesehen und gem\u00e4\u00df den Bestimmungen der Artikel L.335-2 ff. des franz\u00f6sischen Gesetzbuchs \u00fcber geistiges Eigentum (Code de Propri\u00e9t\u00e9 Intellectuelle) verfolgt.<\/p>\n<h3>6. Haftungsbeschr\u00e4nkungen.<\/h3>\n<p>SMART WAG S\u00e0rl kann nicht f\u00fcr direkte und indirekte Sch\u00e4den haftbar gemacht werden, die an der Hardware des Nutzers beim Zugriff auf die Website https:\/\/smartwag.com\/ entstehen und die entweder auf die Verwendung einer Hardware zur\u00fcckzuf\u00fchren sind, die nicht den in Punkt 4 angegebenen Spezifikationen entspricht, oder auf das Auftreten eines Bugs oder einer Inkompatibilit\u00e4t..<\/p>\n<p>SMART WAG S\u00e0rl kann auch nicht f\u00fcr indirekte Sch\u00e4den (wie z. B. Marktverlust oder Verlust einer Chance) haftbar gemacht werden, die durch die Nutzung der Website entstehen. <a href=\"http:\/\/http\/\/smartwag.com\/\/\">https:\/\/smartwag.com\/<\/a>.<\/p>\n<p>Interaktive Bereiche (M\u00f6glichkeit, Fragen im Kontaktbereich zu stellen) stehen den Nutzern zur Verf\u00fcgung. SMART WAG S\u00e0rl beh\u00e4lt sich das Recht vor, ohne vorherige Mahnung jeden in diesem Bereich abgelegten Inhalt zu l\u00f6schen, der gegen die in Frankreich geltenden Gesetze und insbesondere gegen die Bestimmungen zum Datenschutz verst\u00f6\u00dft. Gegebenenfalls beh\u00e4lt sich SMART WAG S\u00e0rl auch die M\u00f6glichkeit vor, den Nutzer zivil- und\/oder strafrechtlich haftbar zu machen, insbesondere bei rassistischen, beleidigenden, diffamierenden oder pornografischen Mitteilungen, unabh\u00e4ngig von den verwendeten Medien (Text, Fotografie...).<\/p>\n<h3>7. Gestion des donn\u00e9es personnelles.<\/h3>\n<p>Nach dem Bundesgesetz \u00fcber den Datenschutz sind Personendaten \"alle Informationen, die sich auf eine bestimmte oder bestimmbare Person beziehen\" (Art.3 DSG) Unter Datenbearbeitung versteht man \"das Beschaffen, Aufbewahren, Nutzen, Ver\u00e4ndern, Bekanntgeben, Archivieren oder Vernichten von Daten\" (Art. 3 DSG) In der Schweiz unterliegt jeder Vorgang im Zusammenhang mit Personendaten dem DSG: Die Daten m\u00fcssen zu dem Zweck bearbeitet werden, zu dem sie gesammelt wurden, sie m\u00fcssen nach der Bearbeitung vernichtet werden, die Person muss \u00fcber den Zweck der Bearbeitung informiert worden sein und dieser zugestimmt haben. Die Richtigkeit der Daten und ihre Sicherheit m\u00fcssen gew\u00e4hrleistet sein. Der betroffenen Person muss das Recht auf Zugang zu den Daten garantiert werden. Das Bundesgesetz \u00fcber den Datenschutz wird derzeit \u00fcberarbeitet, um es an die technologischen und sozialen Entwicklungen anzupassen. Es wird im Zuge der europ\u00e4ischen Datenschutzreform \u00fcberarbeitet, um das durch die neuen EU-Vorschriften garantierte Schutzniveau anzupassen. Der Eidgen\u00f6ssische Datenschutz- und \u00d6ffentlichkeitsbeauftragte (ED\u00d6B) hat eine Informations- und Beratungsfunktion.<\/p>\n<p>Auf europ\u00e4ischer Ebene wird die neue Datenschutz-Grundverordnung (DSGVO) am 25. Mai 2018 in Kraft treten. Alle Unternehmen weltweit, die personenbezogene Daten von EU-B\u00fcrgern verarbeiten, sind von der Einhaltung der Verordnung betroffen. Die Schweiz ist rechtlich nicht direkt von dieser neuen Gesetzgebung betroffen und muss die Verordnung nicht in ihr nationales Recht umsetzen, unterliegt ihr aber als Drittstaat weiterhin. Das Ziel der DSGVO ist es, die Kontrolle der EU-B\u00fcrger \u00fcber die Verwendung ihrer pers\u00f6nlichen Daten zu st\u00e4rken und die Vorschriften f\u00fcr Unternehmen zu vereinheitlichen. Was die \u00dcbermittlung von personenbezogenen Daten zwischen der Schweiz und den USA betrifft, gibt der Swiss-US Privacy Shield einen Rahmen f\u00fcr US-Unternehmen vor, die mit der Schweiz Gesch\u00e4fte machen. Er ist seit April 2017 in Kraft. In der Schweiz gibt es kein \"rechtliches Dateneigentum\", weil man nur Eigent\u00fcmer von Dingen sein kann und Daten nicht als solche betrachtet werden. Es gibt auch keine Eigentumsrechte an Datenbanken, wie es sie in anderen L\u00e4ndern gibt.<\/p>\n<p>Anl\u00e4sslich der Nutzung der Website\u00a0<a href=\"http:\/\/http\/\/smartwag.com\/\/\">https:\/\/smartwag.com\/<\/a>bei der Nutzung der Website k\u00f6nnen folgende Daten erfasst werden: die URL der Links, \u00fcber die der Nutzer auf die Website gelangt ist.\u00a0<a href=\"http:\/\/http\/\/smartwag.com\/\/\">https:\/\/smartwag.com\/<\/a>Die Daten des Nutzers werden in einer Datenbank gespeichert, in der alle Daten des Nutzers, wie z. B. die IP-Adresse des Nutzers, der Zugangsanbieter des Nutzers und die Internetprotokoll-Adresse (IP) des Nutzers, enthalten sind.<\/p>\n<p>In jedem Fall sammelt SMART WAG S\u00e0rl pers\u00f6nliche Informationen \u00fcber den Nutzer nur f\u00fcr die Zwecke bestimmter Dienstleistungen, die auf der Website angeboten werden. <a href=\"http:\/\/http\/\/smartwag.com\/\/\">https:\/\/smartwag.com\/<\/a>. Der Nutzer stellt diese Informationen in voller Kenntnis der Sachlage zur Verf\u00fcgung, insbesondere wenn er sie selbst eingibt. Dem Nutzer der Website wird dann mitgeteilt, dass er die folgenden Angaben machen kann\u00a0<a href=\"http:\/\/http\/\/smartwag.com\/\/\">https:\/\/smartwag.com\/<\/a>\u00a0l\u2019obligation ou non de fournir ces informations.<\/p>\n<p>Keine pers\u00f6nlichen Informationen des Nutzers der Seite\u00a0<a href=\"http:\/\/http\/\/smartwag.com\/\/\">https:\/\/smartwag.com\/<\/a> wird ohne das Wissen des Nutzers ver\u00f6ffentlicht, ausgetauscht, \u00fcbertragen, abgetreten oder auf einem beliebigen Datentr\u00e4ger an Dritte verkauft. Nur wenn SMART WAG S\u00e0rl und seine Rechte \u00fcbernommen werden, k\u00f6nnen diese Informationen an einen eventuellen Erwerber weitergegeben werden, der seinerseits die gleiche Verpflichtung zur Aufbewahrung und \u00c4nderung der Daten gegen\u00fcber dem Nutzer der Website hat.\u00a0<a href=\"http:\/\/http\/\/smartwag.com\/\/\">https:\/\/smartwag.com\/<\/a>.<\/p>\n<h3>8. Liens hypertextes et cookies.<\/h3>\n<p>Die Website\u00a0<a href=\"http:\/\/http\/\/smartwag.com\/\/\">https:\/\/smartwag.com\/<\/a> enth\u00e4lt eine Reihe von Hyperlinks zu anderen Websites, die mit der Genehmigung von SMART WAG S\u00e0rl eingerichtet wurden. SMART WAG S\u00e0rl hat jedoch keine M\u00f6glichkeit, den Inhalt der so besuchten Seiten zu \u00fcberpr\u00fcfen, und \u00fcbernimmt dementsprechend keine Verantwortung daf\u00fcr.<\/p>\n<p>Die Navigation auf der Seite\u00a0<a href=\"http:\/\/http\/\/smartwag.com\/\/\">https:\/\/smartwag.com\/<\/a>\u00a0kann dazu f\u00fchren, dass auf dem Computer des Nutzers ein Cookie(s) installiert wird. Ein Cookie ist eine kleine Datei, die keine Identifizierung des Nutzers erm\u00f6glicht, aber Informationen \u00fcber die Navigation eines Computers auf einer Website speichert. Die so erhaltenen Daten sollen die sp\u00e4tere Navigation auf der Website erleichtern und dienen auch dazu, verschiedene Messungen der Besucherzahlen zu erm\u00f6glichen..<\/p>\n<p>Die Verweigerung der Installation eines Cookies kann dazu f\u00fchren, dass der Zugang zu bestimmten Diensten nicht m\u00f6glich ist. Der Nutzer kann seinen Computer jedoch wie folgt konfigurieren, um die Installation von Cookies abzulehnen:<\/p>\n<p>Im Internet Explorer: Registerkarte Werkzeuge (Zahnrad-Piktogramm oben rechts) \/ Internetoptionen. Klicken Sie auf Datenschutz und w\u00e4hlen Sie Alle Cookies blockieren. Best\u00e4tigen Sie mit Ok.<\/p>\n<p>Unter Firefox: Klicken Sie oben im Browserfenster auf die Firefox-Schaltfl\u00e4che und gehen Sie dann auf die Registerkarte Optionen. Klicken Sie auf die Registerkarte Datenschutz. Stellen Sie die Aufbewahrungsregeln auf: Benutzerdefinierte Einstellungen f\u00fcr den Verlauf verwenden ein. Entfernen Sie schlie\u00dflich das H\u00e4kchen, um Cookies zu deaktivieren.<\/p>\n<p>Unter Safari: Klicken Sie oben rechts im Browser auf das Men\u00fc-Piktogramm (symbolisiert durch ein Zahnrad). W\u00e4hlen Sie Einstellungen aus. Klicken Sie auf Erweiterte Einstellungen anzeigen. Klicken Sie im Abschnitt \"Datenschutz\" auf Inhaltseinstellungen. Im Abschnitt \"Cookies\" k\u00f6nnen Sie Cookies blockieren.<\/p>\n<p>Unter Chrome: Klicken Sie oben rechts im Browser auf das Men\u00fc-Piktogramm (symbolisiert durch drei horizontale Linien). W\u00e4hlen Sie Einstellungen aus. Klicken Sie auf Erweiterte Einstellungen anzeigen. Klicken Sie im Abschnitt \"Datenschutz\" auf Einstellungen. Auf der Registerkarte \"Datenschutz\" k\u00f6nnen Sie Cookies blockieren.<\/p>\n<h3>9. Droit applicable et attribution de juridiction.<\/h3>\n<p>Alle Streitigkeiten im Zusammenhang mit der Nutzung der Website\u00a0<a href=\"http:\/\/http\/\/smartwag.com\/\/\">https:\/\/smartwag.com\/<\/a>\u00a0est soumis au droit Suisse. Il est fait attribution exclusive de juridiction aux tribunaux comp\u00e9tents de Gen\u00e8ve.<\/p>\n<h3>10. Lexique.<\/h3>\n<p>Nutzer: Internetnutzer, der sich einloggt und die oben genannte Website nutzt.<\/p>\n<p>Pers\u00f6nliche Informationen: \"Informationen, die in jeglicher Form, direkt oder indirekt, die Identifizierung der nat\u00fcrlichen Personen erm\u00f6glichen, auf die sie sich beziehen\" (Artikel 4 des Gesetzes Nr. 78-17 vom 6. Januar 1978).<\/p>","protected":false},"excerpt":{"rendered":"<p>1. Pr\u00e9sentation du site. En vertu de l\u2019article 6 de la loi n\u00b0 2004-575 du 21 juin 2004 [&hellip;]<\/p>\n","protected":false},"author":126,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-90","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mentions L\u00e9gales | Smart Wag Artisan \u00c9questre<\/title>\n<meta name=\"description\" content=\"Mentions l\u00e9gales de Smart Wag, artisan fran\u00e7ais sp\u00e9cialis\u00e9 dans l&#039;\u00e9quipement \u00e9questre personnalis\u00e9. Informations l\u00e9gales et conditions...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smartwag.com\/de\/rechtliche-hinweise\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mentions L\u00e9gales | Smart Wag Artisan \u00c9questre\" \/>\n<meta property=\"og:description\" content=\"Mentions l\u00e9gales de Smart Wag, artisan fran\u00e7ais sp\u00e9cialis\u00e9 dans l&#039;\u00e9quipement \u00e9questre personnalis\u00e9. Informations l\u00e9gales et conditions...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smartwag.com\/de\/rechtliche-hinweise\/\" \/>\n<meta property=\"og:site_name\" content=\"Smart Wag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/smartwagofficiel\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-20T10:06:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smartwag.com\\\/mentions-legales\\\/\",\"url\":\"https:\\\/\\\/smartwag.com\\\/mentions-legales\\\/\",\"name\":\"Mentions L\u00e9gales | Smart Wag Artisan \u00c9questre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smartwag.com\\\/#website\"},\"datePublished\":\"2020-05-28T07:47:31+00:00\",\"dateModified\":\"2026-06-20T10:06:46+00:00\",\"description\":\"Mentions l\u00e9gales de Smart Wag, artisan fran\u00e7ais sp\u00e9cialis\u00e9 dans l'\u00e9quipement \u00e9questre personnalis\u00e9. Informations l\u00e9gales et conditions...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smartwag.com\\\/mentions-legales\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smartwag.com\\\/mentions-legales\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smartwag.com\\\/mentions-legales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smartwag.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mentions l\u00e9gales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smartwag.com\\\/#website\",\"url\":\"https:\\\/\\\/smartwag.com\\\/\",\"name\":\"Smart Wag\",\"description\":\"Sp\u00e9cialiste de la gravure personnalis\u00e9e pour cheval et chien\",\"publisher\":{\"@id\":\"https:\\\/\\\/smartwag.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smartwag.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/smartwag.com\\\/#organization\",\"name\":\"Smart Wag\",\"url\":\"https:\\\/\\\/smartwag.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smartwag.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/smartwag.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/logo-noir.png\",\"contentUrl\":\"https:\\\/\\\/smartwag.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/logo-noir.png\",\"width\":490,\"height\":204,\"caption\":\"Smart Wag\"},\"image\":{\"@id\":\"https:\\\/\\\/smartwag.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/smartwagofficiel\",\"https:\\\/\\\/www.instagram.com\\\/smart_wag\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rechtliche Hinweise | Smart Wag Handwerker Reiten","description":"Impressum von Smart Wag, einem franz\u00f6sischen Handwerker, der sich auf personalisierte Reitausr\u00fcstung spezialisiert hat. Rechtliche Informationen und Bedingungen...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smartwag.com\/de\/rechtliche-hinweise\/","og_locale":"de_DE","og_type":"article","og_title":"Mentions L\u00e9gales | Smart Wag Artisan \u00c9questre","og_description":"Mentions l\u00e9gales de Smart Wag, artisan fran\u00e7ais sp\u00e9cialis\u00e9 dans l'\u00e9quipement \u00e9questre personnalis\u00e9. Informations l\u00e9gales et conditions...","og_url":"https:\/\/smartwag.com\/de\/rechtliche-hinweise\/","og_site_name":"Smart Wag","article_publisher":"https:\/\/www.facebook.com\/smartwagofficiel","article_modified_time":"2026-06-20T10:06:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/smartwag.com\/mentions-legales\/","url":"https:\/\/smartwag.com\/mentions-legales\/","name":"Rechtliche Hinweise | Smart Wag Handwerker Reiten","isPartOf":{"@id":"https:\/\/smartwag.com\/#website"},"datePublished":"2020-05-28T07:47:31+00:00","dateModified":"2026-06-20T10:06:46+00:00","description":"Impressum von Smart Wag, einem franz\u00f6sischen Handwerker, der sich auf personalisierte Reitausr\u00fcstung spezialisiert hat. Rechtliche Informationen und Bedingungen...","breadcrumb":{"@id":"https:\/\/smartwag.com\/mentions-legales\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smartwag.com\/mentions-legales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/smartwag.com\/mentions-legales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smartwag.com\/"},{"@type":"ListItem","position":2,"name":"Mentions l\u00e9gales"}]},{"@type":"WebSite","@id":"https:\/\/smartwag.com\/#website","url":"https:\/\/smartwag.com\/","name":"Smart Wag","description":"Spezialist f\u00fcr individuelle Gravuren f\u00fcr Pferde und Hunde","publisher":{"@id":"https:\/\/smartwag.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smartwag.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/smartwag.com\/#organization","name":"Smart Wag","url":"https:\/\/smartwag.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smartwag.com\/#\/schema\/logo\/image\/","url":"https:\/\/smartwag.com\/wp-content\/uploads\/2021\/10\/logo-noir.png","contentUrl":"https:\/\/smartwag.com\/wp-content\/uploads\/2021\/10\/logo-noir.png","width":490,"height":204,"caption":"Smart Wag"},"image":{"@id":"https:\/\/smartwag.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/smartwagofficiel","https:\/\/www.instagram.com\/smart_wag"]}]}},"_links":{"self":[{"href":"https:\/\/smartwag.com\/de\/wp-json\/wp\/v2\/pages\/90","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smartwag.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/smartwag.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/smartwag.com\/de\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/smartwag.com\/de\/wp-json\/wp\/v2\/comments?post=90"}],"version-history":[{"count":1,"href":"https:\/\/smartwag.com\/de\/wp-json\/wp\/v2\/pages\/90\/revisions"}],"predecessor-version":[{"id":27711,"href":"https:\/\/smartwag.com\/de\/wp-json\/wp\/v2\/pages\/90\/revisions\/27711"}],"wp:attachment":[{"href":"https:\/\/smartwag.com\/de\/wp-json\/wp\/v2\/media?parent=90"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}